{"id":9,"date":"2026-03-07T12:00:40","date_gmt":"2026-03-07T12:00:40","guid":{"rendered":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/"},"modified":"2026-03-07T12:00:40","modified_gmt":"2026-03-07T12:00:40","slug":"my-account","status":"publish","type":"page","link":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>My account - Stitched Serenity Crochet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"My account - Stitched Serenity Crochet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/\" \/>\n<meta property=\"og:site_name\" content=\"Stitched Serenity Crochet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/index.php\\\/my-account\\\/\",\"url\":\"https:\\\/\\\/stitchedserenity.co.za\\\/index.php\\\/my-account\\\/\",\"name\":\"My account - Stitched Serenity Crochet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#website\"},\"datePublished\":\"2026-03-07T12:00:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/index.php\\\/my-account\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stitchedserenity.co.za\\\/index.php\\\/my-account\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/index.php\\\/my-account\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stitchedserenity.co.za\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"My account\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#website\",\"url\":\"https:\\\/\\\/stitchedserenity.co.za\\\/\",\"name\":\"Stitched Serenity Crochet\",\"description\":\"Custom Crochet Items\",\"publisher\":{\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stitchedserenity.co.za\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#organization\",\"name\":\"Stitched Serenity Crochet\",\"url\":\"https:\\\/\\\/stitchedserenity.co.za\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stitchedserenity.co.za\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Stiched-Serenity-Website-Logo.png\",\"contentUrl\":\"https:\\\/\\\/stitchedserenity.co.za\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Stiched-Serenity-Website-Logo.png\",\"width\":470,\"height\":110,\"caption\":\"Stitched Serenity Crochet\"},\"image\":{\"@id\":\"https:\\\/\\\/stitchedserenity.co.za\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/whatsapp.com\\\/channel\\\/0029VbBGWn49hXF6WThVlu1a\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"My account - Stitched Serenity Crochet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/","og_locale":"en_US","og_type":"article","og_title":"My account - Stitched Serenity Crochet","og_url":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/","og_site_name":"Stitched Serenity Crochet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/","url":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/","name":"My account - Stitched Serenity Crochet","isPartOf":{"@id":"https:\/\/stitchedserenity.co.za\/#website"},"datePublished":"2026-03-07T12:00:40+00:00","breadcrumb":{"@id":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stitchedserenity.co.za\/index.php\/my-account\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stitchedserenity.co.za\/index.php\/my-account\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stitchedserenity.co.za\/"},{"@type":"ListItem","position":2,"name":"My account"}]},{"@type":"WebSite","@id":"https:\/\/stitchedserenity.co.za\/#website","url":"https:\/\/stitchedserenity.co.za\/","name":"Stitched Serenity Crochet","description":"Custom Crochet Items","publisher":{"@id":"https:\/\/stitchedserenity.co.za\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stitchedserenity.co.za\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/stitchedserenity.co.za\/#organization","name":"Stitched Serenity Crochet","url":"https:\/\/stitchedserenity.co.za\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/stitchedserenity.co.za\/#\/schema\/logo\/image\/","url":"https:\/\/stitchedserenity.co.za\/wp-content\/uploads\/2026\/03\/cropped-Stiched-Serenity-Website-Logo.png","contentUrl":"https:\/\/stitchedserenity.co.za\/wp-content\/uploads\/2026\/03\/cropped-Stiched-Serenity-Website-Logo.png","width":470,"height":110,"caption":"Stitched Serenity Crochet"},"image":{"@id":"https:\/\/stitchedserenity.co.za\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/whatsapp.com\/channel\/0029VbBGWn49hXF6WThVlu1a"]}]}},"_links":{"self":[{"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/stitchedserenity.co.za\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}